{"id":1471,"date":"2020-08-30T11:07:04","date_gmt":"2020-08-30T09:07:04","guid":{"rendered":"https:\/\/www.schachklub-wiehre.de\/?p=1471"},"modified":"2020-08-30T11:07:42","modified_gmt":"2020-08-30T09:07:42","slug":"blitzturnier-im-september","status":"publish","type":"post","link":"https:\/\/www.schachklub-wiehre.de\/en\/blitzturnier-im-september\/","title":{"rendered":"Blitzturnier im September"},"content":{"rendered":"<p>Nachdem wir im August unser erstes Blitzturnier am 1. Freitag des Monats wieder stattfinden lassen konnten, wird auch kommende Woche Freitag, 04.09.2020 um 18:30 Uhr ein weiteres Blitzturnier bei uns im Verein stattfinden. Wie immer ist der Eintritt frei und jeder kann mitmachen. Zu gewinnen gibt auch wieder was auf den erst drei vorderen Pl\u00e4tzen als auch f\u00fcr den letzten Platz. Grunds\u00e4tzlich gilt aber immer, man gewinnt grunds\u00e4tzlich und an jeder Position an Erfahrung \ud83d\ude09<\/p>","protected":false},"excerpt":{"rendered":"<p>Nachdem wir im August unser erstes Blitzturnier am 1. Freitag des Monats wieder stattfinden lassen konnten, wird auch kommende Woche Freitag, 04.09.2020 um 18:30 Uhr ein weiteres Blitzturnier bei uns im Verein stattfinden. Wie immer ist der Eintritt frei und jeder kann mitmachen. Zu gewinnen gibt auch wieder was auf den erst drei vorderen Pl\u00e4tzen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[316,317,318],"class_list":["post-1471","post","type-post","status-publish","format-standard","hentry","category-news","tag-blitzturnier-im-september","tag-eintritt-frei","tag-teilnahme-fuer-jeden"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blitzturnier im September - Schachklub Wiehre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schachklub-wiehre.de\/en\/blitzturnier-im-september\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blitzturnier im September - Schachklub Wiehre\" \/>\n<meta property=\"og:description\" content=\"Nachdem wir im August unser erstes Blitzturnier am 1. Freitag des Monats wieder stattfinden lassen konnten, wird auch kommende Woche Freitag, 04.09.2020 um 18:30 Uhr ein weiteres Blitzturnier bei uns im Verein stattfinden. Wie immer ist der Eintritt frei und jeder kann mitmachen. Zu gewinnen gibt auch wieder was auf den erst drei vorderen Pl\u00e4tzen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schachklub-wiehre.de\/en\/blitzturnier-im-september\/\" \/>\n<meta property=\"og:site_name\" content=\"Schachklub Wiehre\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-30T09:07:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-30T09:07:42+00:00\" \/>\n<meta name=\"author\" content=\"Edelmut Struth\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edelmut Struth\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/\"},\"author\":{\"name\":\"Edelmut Struth\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/b1736320b8b5e6b945d46a53a9488228\"},\"headline\":\"Blitzturnier im September\",\"datePublished\":\"2020-08-30T09:07:04+00:00\",\"dateModified\":\"2020-08-30T09:07:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/\"},\"wordCount\":79,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"keywords\":[\"Blitzturnier im September\",\"Eintritt frei\",\"Teilnahme f\u00fcr jeden\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/\",\"name\":\"Blitzturnier im September - Schachklub Wiehre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\"},\"datePublished\":\"2020-08-30T09:07:04+00:00\",\"dateModified\":\"2020-08-30T09:07:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/blitzturnier-im-september\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blitzturnier im September\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"name\":\"Schachklub Wiehre 2000 e.V.\",\"description\":\"Schachwissen setzt matt!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\",\"name\":\"Schachklub Wiehre\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"width\":109,\"height\":144,\"caption\":\"Schachklub Wiehre\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/b1736320b8b5e6b945d46a53a9488228\",\"name\":\"Edelmut Struth\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"caption\":\"Edelmut Struth\"},\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/author\\\/web584\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blitzturnier im September - Schachklub Wiehre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schachklub-wiehre.de\/en\/blitzturnier-im-september\/","og_locale":"en_GB","og_type":"article","og_title":"Blitzturnier im September - Schachklub Wiehre","og_description":"Nachdem wir im August unser erstes Blitzturnier am 1. Freitag des Monats wieder stattfinden lassen konnten, wird auch kommende Woche Freitag, 04.09.2020 um 18:30 Uhr ein weiteres Blitzturnier bei uns im Verein stattfinden. Wie immer ist der Eintritt frei und jeder kann mitmachen. Zu gewinnen gibt auch wieder was auf den erst drei vorderen Pl\u00e4tzen [&hellip;]","og_url":"https:\/\/www.schachklub-wiehre.de\/en\/blitzturnier-im-september\/","og_site_name":"Schachklub Wiehre","article_published_time":"2020-08-30T09:07:04+00:00","article_modified_time":"2020-08-30T09:07:42+00:00","author":"Edelmut Struth","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edelmut Struth"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/#article","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/"},"author":{"name":"Edelmut Struth","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/b1736320b8b5e6b945d46a53a9488228"},"headline":"Blitzturnier im September","datePublished":"2020-08-30T09:07:04+00:00","dateModified":"2020-08-30T09:07:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/"},"wordCount":79,"commentCount":0,"publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"keywords":["Blitzturnier im September","Eintritt frei","Teilnahme f\u00fcr jeden"],"articleSection":["News"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/","url":"https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/","name":"Blitzturnier im September - Schachklub Wiehre","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website"},"datePublished":"2020-08-30T09:07:04+00:00","dateModified":"2020-08-30T09:07:42+00:00","breadcrumb":{"@id":"https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.schachklub-wiehre.de\/blitzturnier-im-september\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.schachklub-wiehre.de\/"},{"@type":"ListItem","position":2,"name":"Blitzturnier im September"}]},{"@type":"WebSite","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website","url":"https:\/\/www.schachklub-wiehre.de\/en\/","name":"Schachklub Wiehre 2000 e.V.","description":"Schachwissen setzt matt!","publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schachklub-wiehre.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization","name":"Schachklub Wiehre","url":"https:\/\/www.schachklub-wiehre.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","contentUrl":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","width":109,"height":144,"caption":"Schachklub Wiehre"},"image":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/b1736320b8b5e6b945d46a53a9488228","name":"Edelmut Struth","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","caption":"Edelmut Struth"},"url":"https:\/\/www.schachklub-wiehre.de\/en\/author\/web584\/"}]}},"_links":{"self":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/1471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/comments?post=1471"}],"version-history":[{"count":0,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/1471\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/media?parent=1471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/categories?post=1471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/tags?post=1471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}