{"id":1579,"date":"2022-01-23T14:23:33","date_gmt":"2022-01-23T12:23:33","guid":{"rendered":"https:\/\/www.schachklub-wiehre.de\/?p=1579"},"modified":"2022-01-31T19:26:11","modified_gmt":"2022-01-31T17:26:11","slug":"erneut-kein-spielabend","status":"publish","type":"post","link":"https:\/\/www.schachklub-wiehre.de\/en\/erneut-kein-spielabend\/","title":{"rendered":"game location has changed"},"content":{"rendered":"<p>From Monday, January 24th, 2022, our venue in the FT restaurant will have different opening hours. Unfortunately, the restaurant closes at 5:30 p.m. and for us this means that we will not be able to use the FT Hotel on Friday evening. We don't start until 6:00 p.m.<\/p>\n<p>\u00a0<\/p>\n<p>Fortunately, we were able to continue the evening at a different location, namely at the following address:<\/p>\n<address>Freiburg Tennis Club e. V. <br \/>Schwarzwaldstra\u00dfe 179<br \/>79117 Freiburg i. Br.<\/address>\n<p class=\" translation-block\"><br>How do you get there? <a href=\"https:\/\/www.schachklub-wiehre.de\/spiellokal-anfahrt\/\" target=\"_self\">Here<\/a> you will find the relevant information.<\/p>\n<p>Einfach beim Servicepersonal sich nach dem Schachverein erkundigen und ihr werdet zum Nebenraum gef\u00fchrt werden, in dem wir uns aufhalten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ab Montag dem 24.01.2022 wird es an unserer Spielst\u00e4tte im FT-Restaurant vor\u00fcbergehen wieder andere \u00d6ffnungszeiten gelten. Das Restaurant schlie\u00dft leider schon um 17:30 Uhr. Bedauerlicherweise bedeutet dies nun f\u00fcr uns, dass wir am Freitagabend das FT-Hotel nicht zur Verf\u00fcgung haben. Wir fangen ja erst um 18:00 Uhr an. \u00a0 Erfreulicherweise ist es uns gelingen den [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[389,391,392,387],"class_list":["post-1579","post","type-post","status-publish","format-standard","hentry","category-news","tag-79117-freiburg","tag-freiburger-tennisclub-e-v","tag-schwarzwaldstrasse-179","tag-spielabend-im-neuen-spiellokal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spiellokal hat sich ge\u00e4ndert - Schachklub Wiehre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schachklub-wiehre.de\/en\/erneut-kein-spielabend\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spiellokal hat sich ge\u00e4ndert - Schachklub Wiehre\" \/>\n<meta property=\"og:description\" content=\"Ab Montag dem 24.01.2022 wird es an unserer Spielst\u00e4tte im FT-Restaurant vor\u00fcbergehen wieder andere \u00d6ffnungszeiten gelten. Das Restaurant schlie\u00dft leider schon um 17:30 Uhr. Bedauerlicherweise bedeutet dies nun f\u00fcr uns, dass wir am Freitagabend das FT-Hotel nicht zur Verf\u00fcgung haben. Wir fangen ja erst um 18:00 Uhr an. \u00a0 Erfreulicherweise ist es uns gelingen den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schachklub-wiehre.de\/en\/erneut-kein-spielabend\/\" \/>\n<meta property=\"og:site_name\" content=\"Schachklub Wiehre\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-23T12:23:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-31T17:26:11+00:00\" \/>\n<meta name=\"author\" content=\"Dominik M\u00fcller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dominik M\u00fcller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/\"},\"author\":{\"name\":\"Dominik M\u00fcller\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/5e9ab794fe72f2b5402206fc559ed4cb\"},\"headline\":\"Spiellokal hat sich ge\u00e4ndert\",\"datePublished\":\"2022-01-23T12:23:33+00:00\",\"dateModified\":\"2022-01-31T17:26:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/\"},\"wordCount\":113,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"keywords\":[\"79117 Freiburg\",\"Freiburger Tennisclub e.V.\",\"Schwarzwaldstra\u00dfe 179\",\"Spielabend im neuen Spiellokal\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/\",\"name\":\"Spiellokal hat sich ge\u00e4ndert - Schachklub Wiehre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\"},\"datePublished\":\"2022-01-23T12:23:33+00:00\",\"dateModified\":\"2022-01-31T17:26:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/erneut-kein-spielabend\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spiellokal hat sich ge\u00e4ndert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"name\":\"Schachklub Wiehre 2000 e.V.\",\"description\":\"Schachwissen setzt matt!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\",\"name\":\"Schachklub Wiehre\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"width\":109,\"height\":144,\"caption\":\"Schachklub Wiehre\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/5e9ab794fe72f2b5402206fc559ed4cb\",\"name\":\"Dominik M\u00fcller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8354107f31fdb0df0921854ecf1dcbf5b05f2c100cf5d280e00735a03b7b9270?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8354107f31fdb0df0921854ecf1dcbf5b05f2c100cf5d280e00735a03b7b9270?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8354107f31fdb0df0921854ecf1dcbf5b05f2c100cf5d280e00735a03b7b9270?s=96&d=mm&r=g\",\"caption\":\"Dominik M\u00fcller\"},\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/author\\\/mueller\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spiellokal hat sich ge\u00e4ndert - Schachklub Wiehre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schachklub-wiehre.de\/en\/erneut-kein-spielabend\/","og_locale":"en_GB","og_type":"article","og_title":"Spiellokal hat sich ge\u00e4ndert - Schachklub Wiehre","og_description":"Ab Montag dem 24.01.2022 wird es an unserer Spielst\u00e4tte im FT-Restaurant vor\u00fcbergehen wieder andere \u00d6ffnungszeiten gelten. Das Restaurant schlie\u00dft leider schon um 17:30 Uhr. Bedauerlicherweise bedeutet dies nun f\u00fcr uns, dass wir am Freitagabend das FT-Hotel nicht zur Verf\u00fcgung haben. Wir fangen ja erst um 18:00 Uhr an. \u00a0 Erfreulicherweise ist es uns gelingen den [&hellip;]","og_url":"https:\/\/www.schachklub-wiehre.de\/en\/erneut-kein-spielabend\/","og_site_name":"Schachklub Wiehre","article_published_time":"2022-01-23T12:23:33+00:00","article_modified_time":"2022-01-31T17:26:11+00:00","author":"Dominik M\u00fcller","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dominik M\u00fcller","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/#article","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/"},"author":{"name":"Dominik M\u00fcller","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/5e9ab794fe72f2b5402206fc559ed4cb"},"headline":"Spiellokal hat sich ge\u00e4ndert","datePublished":"2022-01-23T12:23:33+00:00","dateModified":"2022-01-31T17:26:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/"},"wordCount":113,"commentCount":0,"publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"keywords":["79117 Freiburg","Freiburger Tennisclub e.V.","Schwarzwaldstra\u00dfe 179","Spielabend im neuen Spiellokal"],"articleSection":["News"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/","url":"https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/","name":"Spiellokal hat sich ge\u00e4ndert - Schachklub Wiehre","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website"},"datePublished":"2022-01-23T12:23:33+00:00","dateModified":"2022-01-31T17:26:11+00:00","breadcrumb":{"@id":"https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.schachklub-wiehre.de\/erneut-kein-spielabend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.schachklub-wiehre.de\/"},{"@type":"ListItem","position":2,"name":"Spiellokal hat sich ge\u00e4ndert"}]},{"@type":"WebSite","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website","url":"https:\/\/www.schachklub-wiehre.de\/en\/","name":"Schachklub Wiehre 2000 e.V.","description":"Schachwissen setzt matt!","publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schachklub-wiehre.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization","name":"Schachklub Wiehre","url":"https:\/\/www.schachklub-wiehre.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","contentUrl":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","width":109,"height":144,"caption":"Schachklub Wiehre"},"image":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/5e9ab794fe72f2b5402206fc559ed4cb","name":"Dominik M\u00fcller","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/8354107f31fdb0df0921854ecf1dcbf5b05f2c100cf5d280e00735a03b7b9270?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8354107f31fdb0df0921854ecf1dcbf5b05f2c100cf5d280e00735a03b7b9270?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8354107f31fdb0df0921854ecf1dcbf5b05f2c100cf5d280e00735a03b7b9270?s=96&d=mm&r=g","caption":"Dominik M\u00fcller"},"url":"https:\/\/www.schachklub-wiehre.de\/en\/author\/mueller\/"}]}},"_links":{"self":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/1579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/comments?post=1579"}],"version-history":[{"count":0,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/1579\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/media?parent=1579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/categories?post=1579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/tags?post=1579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}