{"id":1668,"date":"2023-01-24T12:34:20","date_gmt":"2023-01-24T10:34:20","guid":{"rendered":"https:\/\/www.schachklub-wiehre.de\/?p=1668"},"modified":"2023-01-24T12:35:07","modified_gmt":"2023-01-24T10:35:07","slug":"sk-wiehre-im-tv","status":"publish","type":"post","link":"https:\/\/www.schachklub-wiehre.de\/en\/sk-wiehre-im-tv\/","title":{"rendered":"SK Wiehre im TV"},"content":{"rendered":"<h4 class=\"wp-block-heading\">Schach \u2013 Spiel der K\u00f6nige<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ein gutes Dutzend Schachklubs gibt es in und um Freiburg. Einer davon ist der Schachklub Wiehre 2000. Letztes Jahr in die Verbandsliga aufgestiegen, hat er diese wegen Unstimmigkeiten mit dem badischen Schachverbund nun wieder verlassen. Mit Serien wie \u201eDamengambit\u201c auf Netflix lassen sich immer mehr Leute f\u00fcr das schnellste Spiel der Welt begeistern. Paul Cupec berichtet.<\/p>\n\n\n\n<embed src=\"https:\/\/badentvsued.s3-cdn.welocal.cloud\/media\/53388\/videos\/53388.mp4\" type=\"video\/mp4\">","protected":false},"excerpt":{"rendered":"<p>Schach \u2013 Spiel der K\u00f6nige Ein gutes Dutzend Schachklubs gibt es in und um Freiburg. Einer davon ist der Schachklub Wiehre 2000. Letztes Jahr in die Verbandsliga aufgestiegen, hat er diese wegen Unstimmigkeiten mit dem badischen Schachverbund nun wieder verlassen. Mit Serien wie \u201eDamengambit\u201c auf Netflix lassen sich immer mehr Leute f\u00fcr das schnellste Spiel [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[445,440,441,442,443,444],"class_list":["post-1668","post","type-post","status-publish","format-standard","hentry","category-news","tag-baden-tv-sued","tag-paul-cubec","tag-schach","tag-schachklub","tag-schachklub-wiehre-2000","tag-verbandsliga-sued"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SK Wiehre im TV - Schachklub Wiehre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schachklub-wiehre.de\/en\/sk-wiehre-im-tv\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SK Wiehre im TV - Schachklub Wiehre\" \/>\n<meta property=\"og:description\" content=\"Schach \u2013 Spiel der K\u00f6nige Ein gutes Dutzend Schachklubs gibt es in und um Freiburg. Einer davon ist der Schachklub Wiehre 2000. Letztes Jahr in die Verbandsliga aufgestiegen, hat er diese wegen Unstimmigkeiten mit dem badischen Schachverbund nun wieder verlassen. Mit Serien wie \u201eDamengambit\u201c auf Netflix lassen sich immer mehr Leute f\u00fcr das schnellste Spiel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schachklub-wiehre.de\/en\/sk-wiehre-im-tv\/\" \/>\n<meta property=\"og:site_name\" content=\"Schachklub Wiehre\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-24T10:34:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-24T10:35:07+00:00\" \/>\n<meta name=\"author\" content=\"...\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"...\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/sk-wiehre-im-tv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/sk-wiehre-im-tv\\\/\"},\"author\":{\"name\":\"...\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/bca73df642e4b6dddb7722c8322e2b4b\"},\"headline\":\"SK Wiehre im TV\",\"datePublished\":\"2023-01-24T10:34:20+00:00\",\"dateModified\":\"2023-01-24T10:35:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/sk-wiehre-im-tv\\\/\"},\"wordCount\":65,\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"keywords\":[\"Baden TV Sued\",\"Paul Cubec\",\"schach\",\"Schachklub\",\"Schachklub Wiehre 2000\",\"Verbandsliga S\u00fcd\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/sk-wiehre-im-tv\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/sk-wiehre-im-tv\\\/\",\"name\":\"SK Wiehre im TV - Schachklub Wiehre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\"},\"datePublished\":\"2023-01-24T10:34:20+00:00\",\"dateModified\":\"2023-01-24T10:35:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/sk-wiehre-im-tv\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/sk-wiehre-im-tv\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/sk-wiehre-im-tv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SK Wiehre im TV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"name\":\"Schachklub Wiehre 2000 e.V.\",\"description\":\"Schachwissen setzt matt!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\",\"name\":\"Schachklub Wiehre\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"width\":109,\"height\":144,\"caption\":\"Schachklub Wiehre\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/bca73df642e4b6dddb7722c8322e2b4b\",\"name\":\"...\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/308a945e0ff48b40adf1e44d0b47f336a53aec15ce801a99a18052c8a924e4e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/308a945e0ff48b40adf1e44d0b47f336a53aec15ce801a99a18052c8a924e4e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/308a945e0ff48b40adf1e44d0b47f336a53aec15ce801a99a18052c8a924e4e9?s=96&d=mm&r=g\",\"caption\":\"...\"},\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SK Wiehre im TV - Schachklub Wiehre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schachklub-wiehre.de\/en\/sk-wiehre-im-tv\/","og_locale":"en_GB","og_type":"article","og_title":"SK Wiehre im TV - Schachklub Wiehre","og_description":"Schach \u2013 Spiel der K\u00f6nige Ein gutes Dutzend Schachklubs gibt es in und um Freiburg. Einer davon ist der Schachklub Wiehre 2000. Letztes Jahr in die Verbandsliga aufgestiegen, hat er diese wegen Unstimmigkeiten mit dem badischen Schachverbund nun wieder verlassen. Mit Serien wie \u201eDamengambit\u201c auf Netflix lassen sich immer mehr Leute f\u00fcr das schnellste Spiel [&hellip;]","og_url":"https:\/\/www.schachklub-wiehre.de\/en\/sk-wiehre-im-tv\/","og_site_name":"Schachklub Wiehre","article_published_time":"2023-01-24T10:34:20+00:00","article_modified_time":"2023-01-24T10:35:07+00:00","author":"...","twitter_card":"summary_large_image","twitter_misc":{"Written by":"..."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.schachklub-wiehre.de\/sk-wiehre-im-tv\/#article","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/sk-wiehre-im-tv\/"},"author":{"name":"...","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/bca73df642e4b6dddb7722c8322e2b4b"},"headline":"SK Wiehre im TV","datePublished":"2023-01-24T10:34:20+00:00","dateModified":"2023-01-24T10:35:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schachklub-wiehre.de\/sk-wiehre-im-tv\/"},"wordCount":65,"publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"keywords":["Baden TV Sued","Paul Cubec","schach","Schachklub","Schachklub Wiehre 2000","Verbandsliga S\u00fcd"],"articleSection":["News"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.schachklub-wiehre.de\/sk-wiehre-im-tv\/","url":"https:\/\/www.schachklub-wiehre.de\/sk-wiehre-im-tv\/","name":"SK Wiehre im TV - Schachklub Wiehre","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website"},"datePublished":"2023-01-24T10:34:20+00:00","dateModified":"2023-01-24T10:35:07+00:00","breadcrumb":{"@id":"https:\/\/www.schachklub-wiehre.de\/sk-wiehre-im-tv\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schachklub-wiehre.de\/sk-wiehre-im-tv\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.schachklub-wiehre.de\/sk-wiehre-im-tv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.schachklub-wiehre.de\/"},{"@type":"ListItem","position":2,"name":"SK Wiehre im TV"}]},{"@type":"WebSite","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website","url":"https:\/\/www.schachklub-wiehre.de\/en\/","name":"Schachklub Wiehre 2000 e.V.","description":"Schachwissen setzt matt!","publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schachklub-wiehre.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization","name":"Schachklub Wiehre","url":"https:\/\/www.schachklub-wiehre.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","contentUrl":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","width":109,"height":144,"caption":"Schachklub Wiehre"},"image":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/bca73df642e4b6dddb7722c8322e2b4b","name":"...","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/308a945e0ff48b40adf1e44d0b47f336a53aec15ce801a99a18052c8a924e4e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/308a945e0ff48b40adf1e44d0b47f336a53aec15ce801a99a18052c8a924e4e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/308a945e0ff48b40adf1e44d0b47f336a53aec15ce801a99a18052c8a924e4e9?s=96&d=mm&r=g","caption":"..."},"url":"https:\/\/www.schachklub-wiehre.de\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/1668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/comments?post=1668"}],"version-history":[{"count":0,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/1668\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/media?parent=1668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/categories?post=1668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/tags?post=1668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}