{"id":1722,"date":"2023-08-23T21:59:38","date_gmt":"2023-08-23T19:59:38","guid":{"rendered":"https:\/\/www.schachklub-wiehre.de\/?p=1722"},"modified":"2023-08-24T22:29:22","modified_gmt":"2023-08-24T20:29:22","slug":"saison-2023-2024-beginnt","status":"publish","type":"post","link":"https:\/\/www.schachklub-wiehre.de\/en\/saison-2023-2024-beginnt\/","title":{"rendered":"Saison 2023\/2024 beginnt"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Es ist wieder so weit! Schachliebhaber aus der Region k\u00f6nnen sich auf viele Partien freuen, die den Geist des Spiels und die Gemeinschaftsverbundenheit leben. Die Saison 2023\/2024 im Badischen Schachverband verspricht vieles, eine Gelegenheit f\u00fcr Schachfreunde, sich in einem vertrauten Umfeld zu treffen, zu spielen und zu wetteifern. Welche Mannschaften spielen in welcher Liga? Welche Ambitionen gibt es? Die Saison 2023\/2024 im Badischen Schachverband verspricht also nicht nur Schach auf hohem Niveau, sondern auch eine Gelegenheit f\u00fcr Schachfreunde, sich in einem vertrauten Umfeld zu treffen, zu spielen und zu wetteifern. Die neun Runden werden zweifellos eine F\u00fclle von faszinierenden Partien und unvergesslichen Momenten bieten.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<p>Unsere Webseite zeigt dir, welche <a href=\"https:\/\/www.schachklub-wiehre.de\/spielbetrieb\/\">Mannschaften<\/a> wo spielen? Jeder einzelne Spieler, von den erfahrensten Veteranen bis zu den aufstrebenden Talenten, ist herzlich willkommen und spielt eine wichtige Rolle in diesem aufregenden Turnier. Jeder Zug am Schachbrett, jede strategische Entscheidung und jedes taktische Man\u00f6ver tragen dazu bei, den Erfolg des eigenen Teams zu gestalten. Die Mannschaftsk\u00e4mpfe sind eine Gelegenheit, nicht nur die individuellen F\u00e4higkeiten zu zeigen, sondern auch den Teamgeist und die Gemeinschaft zu st\u00e4rken. Jeder Sieg z\u00e4hlt! Jeder Spieler tr\u00e4gt dazu bei, diese Saison zu einem unvergesslichen Schacherlebnis zu machen.<\/p>\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Apropos Erlebnis! Diese meine Partie soll Lust machen auf mehr, auf die neue Saison, euch zeigen, meine Erfahrung und meine Lieblingspartie. &#8222;Raum und Zeit&#8220; \u00fcberragt das &#8222;materielle \u00dcbergewicht&#8220;. Ein Turm und 2 Bauern weniger f\u00fcr mich und &#8222;Party is over!&#8220; f\u00fcr meinen Gegner. Life is to live. Habt Spa\u00df!<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n<p class=\"rpbchessboard-spacerBefore\"><\/p>\n\n<div class=\"rpbchessboard-chessgame\">\n    <noscript>\n        <div class=\"rpbchessboard-javascriptWarning\">\n            You must activate JavaScript to enhance chess game visualization.        <\/div>\n    <\/noscript>\n    <div id=\"rpbchessboard-6a580651e9c82-1\"><\/div>\n    <script type=\"text\/javascript\">\n        (function() {\n            function renderThisPGN() {\n                RPBChessboard.renderPGN(\"rpbchessboard-6a580651e9c82-1\", {\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/raum-und-zeit.pgn\",\"gameIndex\":0,\"pieceSymbols\":\"localized\",\"navigationBoard\":\"above\",\"withPlayButton\":true,\"withFlipButton\":true,\"withDownloadButton\":false,\"nboSquareSize\":40,\"nboCoordinateVisible\":true,\"nboTurnVisible\":true,\"nboColorset\":\"original\",\"nboPieceset\":\"cburnett\",\"nboAnimated\":true,\"nboMoveArrowVisible\":true,\"nboMoveArrowColor\":\"b\",\"nboSound\":true,\"idoSquareSize\":48,\"idoCoordinateVisible\":true,\"idoTurnVisible\":true,\"idoColorset\":\"original\",\"idoPieceset\":\"cburnett\"});\n            }\n            if (document.readyState === 'loading') {\n                document.addEventListener('DOMContentLoaded', renderThisPGN);\n            }\n            else {\n                renderThisPGN();\n            }\n        })();\n    <\/script>\n<\/div>\n\n<p class=\"rpbchessboard-spacerAfter\"><\/p>\n\n\n\n<div style=\"height:34px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Es ist wieder so weit! Schachliebhaber aus der Region k\u00f6nnen sich auf viele Partien freuen, die den Geist des Spiels und die Gemeinschaftsverbundenheit leben. Die Saison 2023\/2024 im Badischen Schachverband verspricht vieles, eine Gelegenheit f\u00fcr Schachfreunde, sich in einem vertrauten Umfeld zu treffen, zu spielen und zu wetteifern. Welche Mannschaften spielen in welcher Liga? Welche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[461,463,460,462],"class_list":["post-1722","post","type-post","status-publish","format-standard","hentry","category-news","tag-beginn-am-24-09-2023","tag-jeder-spieler-zaehlt","tag-schachsaison-2023-2024","tag-spielen-mit-3-mannschaften"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saison 2023\/2024 beginnt - Schachklub Wiehre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schachklub-wiehre.de\/en\/saison-2023-2024-beginnt\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saison 2023\/2024 beginnt - Schachklub Wiehre\" \/>\n<meta property=\"og:description\" content=\"Es ist wieder so weit! Schachliebhaber aus der Region k\u00f6nnen sich auf viele Partien freuen, die den Geist des Spiels und die Gemeinschaftsverbundenheit leben. Die Saison 2023\/2024 im Badischen Schachverband verspricht vieles, eine Gelegenheit f\u00fcr Schachfreunde, sich in einem vertrauten Umfeld zu treffen, zu spielen und zu wetteifern. Welche Mannschaften spielen in welcher Liga? Welche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schachklub-wiehre.de\/en\/saison-2023-2024-beginnt\/\" \/>\n<meta property=\"og:site_name\" content=\"Schachklub Wiehre\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-23T19:59:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-24T20:29:22+00:00\" \/>\n<meta name=\"author\" content=\"Edelmut Struth\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edelmut Struth\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/\"},\"author\":{\"name\":\"Edelmut Struth\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/b1736320b8b5e6b945d46a53a9488228\"},\"headline\":\"Saison 2023\\\/2024 beginnt\",\"datePublished\":\"2023-08-23T19:59:38+00:00\",\"dateModified\":\"2023-08-24T20:29:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"keywords\":[\"Beginn am 24.09.2023\",\"jeder Spieler z\u00e4hlt!\",\"Schachsaison 2023\\\/2024\",\"spielen mit 3 Mannschaften\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/\",\"name\":\"Saison 2023\\\/2024 beginnt - Schachklub Wiehre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\"},\"datePublished\":\"2023-08-23T19:59:38+00:00\",\"dateModified\":\"2023-08-24T20:29:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/saison-2023-2024-beginnt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saison 2023\\\/2024 beginnt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"name\":\"Schachklub Wiehre 2000 e.V.\",\"description\":\"Schachwissen setzt matt!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\",\"name\":\"Schachklub Wiehre\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"width\":109,\"height\":144,\"caption\":\"Schachklub Wiehre\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/b1736320b8b5e6b945d46a53a9488228\",\"name\":\"Edelmut Struth\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"caption\":\"Edelmut Struth\"},\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/author\\\/web584\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saison 2023\/2024 beginnt - Schachklub Wiehre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schachklub-wiehre.de\/en\/saison-2023-2024-beginnt\/","og_locale":"en_GB","og_type":"article","og_title":"Saison 2023\/2024 beginnt - Schachklub Wiehre","og_description":"Es ist wieder so weit! Schachliebhaber aus der Region k\u00f6nnen sich auf viele Partien freuen, die den Geist des Spiels und die Gemeinschaftsverbundenheit leben. Die Saison 2023\/2024 im Badischen Schachverband verspricht vieles, eine Gelegenheit f\u00fcr Schachfreunde, sich in einem vertrauten Umfeld zu treffen, zu spielen und zu wetteifern. Welche Mannschaften spielen in welcher Liga? Welche [&hellip;]","og_url":"https:\/\/www.schachklub-wiehre.de\/en\/saison-2023-2024-beginnt\/","og_site_name":"Schachklub Wiehre","article_published_time":"2023-08-23T19:59:38+00:00","article_modified_time":"2023-08-24T20:29:22+00:00","author":"Edelmut Struth","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edelmut Struth","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/#article","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/"},"author":{"name":"Edelmut Struth","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/b1736320b8b5e6b945d46a53a9488228"},"headline":"Saison 2023\/2024 beginnt","datePublished":"2023-08-23T19:59:38+00:00","dateModified":"2023-08-24T20:29:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"keywords":["Beginn am 24.09.2023","jeder Spieler z\u00e4hlt!","Schachsaison 2023\/2024","spielen mit 3 Mannschaften"],"articleSection":["News"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/","url":"https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/","name":"Saison 2023\/2024 beginnt - Schachklub Wiehre","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website"},"datePublished":"2023-08-23T19:59:38+00:00","dateModified":"2023-08-24T20:29:22+00:00","breadcrumb":{"@id":"https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.schachklub-wiehre.de\/saison-2023-2024-beginnt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.schachklub-wiehre.de\/"},{"@type":"ListItem","position":2,"name":"Saison 2023\/2024 beginnt"}]},{"@type":"WebSite","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website","url":"https:\/\/www.schachklub-wiehre.de\/en\/","name":"Schachklub Wiehre 2000 e.V.","description":"Schachwissen setzt matt!","publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schachklub-wiehre.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization","name":"Schachklub Wiehre","url":"https:\/\/www.schachklub-wiehre.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","contentUrl":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","width":109,"height":144,"caption":"Schachklub Wiehre"},"image":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/b1736320b8b5e6b945d46a53a9488228","name":"Edelmut Struth","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","caption":"Edelmut Struth"},"url":"https:\/\/www.schachklub-wiehre.de\/en\/author\/web584\/"}]}},"_links":{"self":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/1722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/comments?post=1722"}],"version-history":[{"count":0,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/1722\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/media?parent=1722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/categories?post=1722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/tags?post=1722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}