{"id":232,"date":"2013-04-02T15:53:49","date_gmt":"2013-04-02T13:53:49","guid":{"rendered":"http:\/\/schachklub-wiehre.de\/?p=232"},"modified":"2013-04-02T15:53:49","modified_gmt":"2013-04-02T13:53:49","slug":"klassenerhalt-so-gut-wie-sicher","status":"publish","type":"post","link":"https:\/\/www.schachklub-wiehre.de\/en\/klassenerhalt-so-gut-wie-sicher\/","title":{"rendered":"Klassenerhalt so gut wie sicher"},"content":{"rendered":"<p>April 2013<br \/>\nEndlich mal wieder ein Grund zur Freude &#8211; unsere Erste hat den Klassenerhalt so gut wie sicher! In einer spannenden und ausgeglichenen Bereichsliga haben wir damit das Saisonziel erreicht. Am 24.3. hatten wir das wichtige Ausw\u00e4rtsspiel gegen die punktgleiche Mannschaft von Schwarze Pumpe Freiburg. Beide Mannschaften traten in starker Besetzung an, so dass ein knappes Ergebnis zu erwarten war, wie im letzten Jahr. Zun\u00e4chst holten Ralf und Edi zwei halbe Punkte, doch nach 2 Niederlagen stand es 1:3 und wir mussten zittern. Dann kam die Aufholjagd: Thomas parierte den Mattangriff seines Gegners souver\u00e4n und hatte enormen Materialvorteil, was zur Aufgabe f\u00fchrte. Alex an Brett 8 wickelte in ein Endspiel mit Mehrbauer ab und gewann sicher &#8211; 3:3. Dann gewann St\u00e9phane an Brett 1 nach einem Zeitnotkrimi und brachte uns erstmals in F\u00fchrung. Als dann noch Bruno Remis spielte war der 4,5:3,5 Sieg perfekt! Wir m\u00fcssten nur im Extremfall noch ein Relegationsspiel gegen den Abstieg absolvieren, aber das ist mehr als unwahrscheinlich. Wir freuen uns, dass wir auch im n\u00e4chsten Jahr wieder in der Bereichsliga spielen d\u00fcrfen, in der wir es durchg\u00e4ngig mit netten, fairen und sympathischen Gegnern zu tun hatten.<\/p>","protected":false},"excerpt":{"rendered":"<p>April 2013 Endlich mal wieder ein Grund zur Freude &#8211; unsere Erste hat den Klassenerhalt so gut wie sicher! In einer spannenden und ausgeglichenen Bereichsliga haben wir damit das Saisonziel erreicht. Am 24.3. hatten wir das wichtige Ausw\u00e4rtsspiel gegen die punktgleiche Mannschaft von Schwarze Pumpe Freiburg. Beide Mannschaften traten in starker Besetzung an, so dass [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-232","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klassenerhalt so gut wie sicher - Schachklub Wiehre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schachklub-wiehre.de\/en\/klassenerhalt-so-gut-wie-sicher\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klassenerhalt so gut wie sicher - Schachklub Wiehre\" \/>\n<meta property=\"og:description\" content=\"April 2013 Endlich mal wieder ein Grund zur Freude &#8211; unsere Erste hat den Klassenerhalt so gut wie sicher! In einer spannenden und ausgeglichenen Bereichsliga haben wir damit das Saisonziel erreicht. Am 24.3. hatten wir das wichtige Ausw\u00e4rtsspiel gegen die punktgleiche Mannschaft von Schwarze Pumpe Freiburg. Beide Mannschaften traten in starker Besetzung an, so dass [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schachklub-wiehre.de\/en\/klassenerhalt-so-gut-wie-sicher\/\" \/>\n<meta property=\"og:site_name\" content=\"Schachklub Wiehre\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-02T13:53:49+00:00\" \/>\n<meta name=\"author\" content=\"Edelmut Struth\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edelmut Struth\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/\"},\"author\":{\"name\":\"Edelmut Struth\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/b1736320b8b5e6b945d46a53a9488228\"},\"headline\":\"Klassenerhalt so gut wie sicher\",\"datePublished\":\"2013-04-02T13:53:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/\"},\"wordCount\":199,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/\",\"name\":\"Klassenerhalt so gut wie sicher - Schachklub Wiehre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\"},\"datePublished\":\"2013-04-02T13:53:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/klassenerhalt-so-gut-wie-sicher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Klassenerhalt so gut wie sicher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"name\":\"Schachklub Wiehre 2000 e.V.\",\"description\":\"Schachwissen setzt matt!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\",\"name\":\"Schachklub Wiehre\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"width\":109,\"height\":144,\"caption\":\"Schachklub Wiehre\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/b1736320b8b5e6b945d46a53a9488228\",\"name\":\"Edelmut Struth\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"caption\":\"Edelmut Struth\"},\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/author\\\/web584\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klassenerhalt so gut wie sicher - Schachklub Wiehre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schachklub-wiehre.de\/en\/klassenerhalt-so-gut-wie-sicher\/","og_locale":"en_GB","og_type":"article","og_title":"Klassenerhalt so gut wie sicher - Schachklub Wiehre","og_description":"April 2013 Endlich mal wieder ein Grund zur Freude &#8211; unsere Erste hat den Klassenerhalt so gut wie sicher! In einer spannenden und ausgeglichenen Bereichsliga haben wir damit das Saisonziel erreicht. Am 24.3. hatten wir das wichtige Ausw\u00e4rtsspiel gegen die punktgleiche Mannschaft von Schwarze Pumpe Freiburg. Beide Mannschaften traten in starker Besetzung an, so dass [&hellip;]","og_url":"https:\/\/www.schachklub-wiehre.de\/en\/klassenerhalt-so-gut-wie-sicher\/","og_site_name":"Schachklub Wiehre","article_published_time":"2013-04-02T13:53:49+00:00","author":"Edelmut Struth","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edelmut Struth","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/#article","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/"},"author":{"name":"Edelmut Struth","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/b1736320b8b5e6b945d46a53a9488228"},"headline":"Klassenerhalt so gut wie sicher","datePublished":"2013-04-02T13:53:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/"},"wordCount":199,"commentCount":0,"publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"articleSection":["News"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/","url":"https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/","name":"Klassenerhalt so gut wie sicher - Schachklub Wiehre","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website"},"datePublished":"2013-04-02T13:53:49+00:00","breadcrumb":{"@id":"https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.schachklub-wiehre.de\/klassenerhalt-so-gut-wie-sicher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.schachklub-wiehre.de\/"},{"@type":"ListItem","position":2,"name":"Klassenerhalt so gut wie sicher"}]},{"@type":"WebSite","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website","url":"https:\/\/www.schachklub-wiehre.de\/en\/","name":"Schachklub Wiehre 2000 e.V.","description":"Schachwissen setzt matt!","publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schachklub-wiehre.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization","name":"Schachklub Wiehre","url":"https:\/\/www.schachklub-wiehre.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","contentUrl":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","width":109,"height":144,"caption":"Schachklub Wiehre"},"image":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/b1736320b8b5e6b945d46a53a9488228","name":"Edelmut Struth","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","caption":"Edelmut Struth"},"url":"https:\/\/www.schachklub-wiehre.de\/en\/author\/web584\/"}]}},"_links":{"self":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":0,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/232\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/categories?post=232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/tags?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}