{"id":623,"date":"2014-02-07T16:57:18","date_gmt":"2014-02-07T15:57:18","guid":{"rendered":"http:\/\/www.schachklub-wiehre.de\/?p=623"},"modified":"2015-05-02T09:27:49","modified_gmt":"2015-05-02T07:27:49","slug":"2-februar-2014-wieder-ein-glueckstag","status":"publish","type":"post","link":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/","title":{"rendered":"Wieder ein Gl\u00fcckstag"},"content":{"rendered":"<p>Am 2.2.2014 standen f\u00fcr uns 2 Ausw\u00e4rtsspiele an, die beide mit 5,5:2,5 gewonnen wurden. Hierbei spielten wir erstmals in dieser Saison mit 2 vollst\u00e4ndigen Mannschaften.<br \/>\nDie Erste musste in der Bereichsliga nach Laufenburg reisen, was unsere weiteste Ausw\u00e4rtsfahrt war. Mit leichter Versp\u00e4tung dort angekommen (Laufenburg war hierbei wie \u00fcblich fair), ging es dann an den hinteren Brettern schnell zur Sache. Nach Ralfs Remis an Brett 5 siegten Alex A., Patrick und Hannes an den Brettern 6-8, so dass wir mit 3,5:0,5 komfortabel f\u00fchrten. Doch danach wurde es schwieriger: Edi und Bruno konnten ihre Partien nicht halten &#8211; nur noch 3,5:2,5. St\u00e9phane bewies jedoch an Brett 1 einmal mehr seine Klasse und gewann, so dass der Mannschaftssieg unter Dach und Fach war. Nach langem Kampf siegte dann auch Alex O. und stellte damit den 5,5:2,5 Endstand her. Mit diesem Sieg stehen wir mit 6:4 Punkten hervorragend da!<br \/>\nDie Zweite trat in Emmendingen an und war ebenfalls erfolgreich. Enrico und Uwe hielten an den Spitzenbrettern Remis, ebenso wie Carlo Maria an Brett 6. Isak verlor ungl\u00fccklich an Brett 3, aber Declan, Dominik und Hans-Joachim siegten an den Brettern 4,5 und 7. Bemerkenswert war der Sieg von Flamur in seiner erst 2. Turnierpartie \u00fcberhaupt!<br \/>\nDie Zweite steht nun nach verpatztem Saisonbeginn mit 5:5 Punkten im Mittelfeld.<br \/>\n\u00dcberhaupt k\u00f6nnen wir nach den Auftaktniederlagen jetzt mit 6:4 und 5:5 Punkten eine insgesamt leicht positive Bilanz aufweisen &#8211; das ist ein v\u00f6llig neues Gef\u00fchl, so kann es weitergehen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 2.2.2014 standen f\u00fcr uns 2 Ausw\u00e4rtsspiele an, die beide mit 5,5:2,5 gewonnen wurden. Hierbei spielten wir erstmals in dieser Saison mit 2 vollst\u00e4ndigen Mannschaften. Die Erste musste in der Bereichsliga nach Laufenburg reisen, was unsere weiteste Ausw\u00e4rtsfahrt war. Mit leichter Versp\u00e4tung dort angekommen (Laufenburg war hierbei wie \u00fcblich fair), ging es dann an den [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-623","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wieder ein Gl\u00fcckstag - Schachklub Wiehre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wieder ein Gl\u00fcckstag - Schachklub Wiehre\" \/>\n<meta property=\"og:description\" content=\"Am 2.2.2014 standen f\u00fcr uns 2 Ausw\u00e4rtsspiele an, die beide mit 5,5:2,5 gewonnen wurden. Hierbei spielten wir erstmals in dieser Saison mit 2 vollst\u00e4ndigen Mannschaften. Die Erste musste in der Bereichsliga nach Laufenburg reisen, was unsere weiteste Ausw\u00e4rtsfahrt war. Mit leichter Versp\u00e4tung dort angekommen (Laufenburg war hierbei wie \u00fcblich fair), ging es dann an den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/\" \/>\n<meta property=\"og:site_name\" content=\"Schachklub Wiehre\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-07T15:57:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-02T07:27:49+00:00\" \/>\n<meta name=\"author\" content=\"Edelmut Struth\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edelmut Struth\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/\"},\"author\":{\"name\":\"Edelmut Struth\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/b1736320b8b5e6b945d46a53a9488228\"},\"headline\":\"Wieder ein Gl\u00fcckstag\",\"datePublished\":\"2014-02-07T15:57:18+00:00\",\"dateModified\":\"2015-05-02T07:27:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/\"},\"wordCount\":239,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/\",\"name\":\"Wieder ein Gl\u00fcckstag - Schachklub Wiehre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\"},\"datePublished\":\"2014-02-07T15:57:18+00:00\",\"dateModified\":\"2015-05-02T07:27:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/2-februar-2014-wieder-ein-glueckstag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wieder ein Gl\u00fcckstag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"name\":\"Schachklub Wiehre 2000 e.V.\",\"description\":\"Schachwissen setzt matt!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#organization\",\"name\":\"Schachklub Wiehre\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/wp-content\\\/uploads\\\/Wappen-skw-0.jpg\",\"width\":109,\"height\":144,\"caption\":\"Schachklub Wiehre\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/#\\\/schema\\\/person\\\/b1736320b8b5e6b945d46a53a9488228\",\"name\":\"Edelmut Struth\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g\",\"caption\":\"Edelmut Struth\"},\"url\":\"https:\\\/\\\/www.schachklub-wiehre.de\\\/en\\\/author\\\/web584\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wieder ein Gl\u00fcckstag - Schachklub Wiehre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/","og_locale":"en_GB","og_type":"article","og_title":"Wieder ein Gl\u00fcckstag - Schachklub Wiehre","og_description":"Am 2.2.2014 standen f\u00fcr uns 2 Ausw\u00e4rtsspiele an, die beide mit 5,5:2,5 gewonnen wurden. Hierbei spielten wir erstmals in dieser Saison mit 2 vollst\u00e4ndigen Mannschaften. Die Erste musste in der Bereichsliga nach Laufenburg reisen, was unsere weiteste Ausw\u00e4rtsfahrt war. Mit leichter Versp\u00e4tung dort angekommen (Laufenburg war hierbei wie \u00fcblich fair), ging es dann an den [&hellip;]","og_url":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/","og_site_name":"Schachklub Wiehre","article_published_time":"2014-02-07T15:57:18+00:00","article_modified_time":"2015-05-02T07:27:49+00:00","author":"Edelmut Struth","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edelmut Struth","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/#article","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/"},"author":{"name":"Edelmut Struth","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/b1736320b8b5e6b945d46a53a9488228"},"headline":"Wieder ein Gl\u00fcckstag","datePublished":"2014-02-07T15:57:18+00:00","dateModified":"2015-05-02T07:27:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/"},"wordCount":239,"commentCount":0,"publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"articleSection":["News"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/","url":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/","name":"Wieder ein Gl\u00fcckstag - Schachklub Wiehre","isPartOf":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website"},"datePublished":"2014-02-07T15:57:18+00:00","dateModified":"2015-05-02T07:27:49+00:00","breadcrumb":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.schachklub-wiehre.de\/en\/2-februar-2014-wieder-ein-glueckstag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.schachklub-wiehre.de\/"},{"@type":"ListItem","position":2,"name":"Wieder ein Gl\u00fcckstag"}]},{"@type":"WebSite","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#website","url":"https:\/\/www.schachklub-wiehre.de\/en\/","name":"Schachklub Wiehre 2000 e.V.","description":"Schachwissen setzt matt!","publisher":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schachklub-wiehre.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#organization","name":"Schachklub Wiehre","url":"https:\/\/www.schachklub-wiehre.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","contentUrl":"https:\/\/www.schachklub-wiehre.de\/wp-content\/uploads\/Wappen-skw-0.jpg","width":109,"height":144,"caption":"Schachklub Wiehre"},"image":{"@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.schachklub-wiehre.de\/en\/#\/schema\/person\/b1736320b8b5e6b945d46a53a9488228","name":"Edelmut Struth","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23cb9fade271742caa829610bbff74e1132b56e3a4c1d9e1cc75329e53430bd3?s=96&d=mm&r=g","caption":"Edelmut Struth"},"url":"https:\/\/www.schachklub-wiehre.de\/en\/author\/web584\/"}]}},"_links":{"self":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/comments?post=623"}],"version-history":[{"count":0,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/posts\/623\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/media?parent=623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/categories?post=623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schachklub-wiehre.de\/en\/wp-json\/wp\/v2\/tags?post=623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}